{"id":845,"date":"2025-11-04T10:53:57","date_gmt":"2025-11-04T08:53:57","guid":{"rendered":"https:\/\/www.inspirealtea.com\/?p=845"},"modified":"2026-02-28T20:03:51","modified_gmt":"2026-02-28T19:03:51","slug":"yoga-allaperto-mare-mediterraneo","status":"publish","type":"post","link":"https:\/\/www.inspirealtea.com\/it\/outdoor-yoga-mediterranean-sea\/","title":{"rendered":"Yoga in riva al Mediterraneo | Una nuova dimensione della pratica"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-reconnect-with-nature-into-the-outdoors\"><strong>Riconnettersi con la natura all'aria aperta<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esperienza <strong>yoga all'aperto Mar Mediterraneo<\/strong> con <strong>Dhariya<\/strong>, insegnante di yoga certificata a livello internazionale e influenzata dai maestri indiani tradizionali. La pratica dello yoga all'aperto risveglia i sensi, approfondisce il respiro e ripristina l'equilibrio interiore. Sentite il <strong>sole sulla pelle<\/strong>, La brezza marina sul viso e il dolce ritmo delle onde che guidano il flusso: il massimo del ringiovanimento mente-corpo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le miscele di insegnamento di Dhariya <strong>Hatha, Ashtanga, Vinyasa, Yin, Kundalini, Tantra e Yoga del Suono<\/strong>, radicata nella filosofia classica indiana e nelle moderne tecniche di mindfulness. Ogni sessione \u00e8 pensata per aiutarvi a <strong>riconnettersi con il proprio corpo, la propria mente e la propria energia interiore<\/strong> mentre si esercita in un ambiente naturale e sereno.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-benefits\"><strong>Vantaggi<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"868\" height=\"1300\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-8018924.jpeg?fit=868%2C1300&amp;ssl=1\" alt=\"una donna che fa yoga vicino all&#039;oceano\" class=\"wp-image-849\" srcset=\"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-8018924.jpeg?w=868&amp;ssl=1 868w, https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-8018924.jpeg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-8018924.jpeg?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-8018924.jpeg?resize=768%2C1150&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-8018924.jpeg?resize=600%2C899&amp;ssl=1 600w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pratica <strong>yoga all'aperto Mar Mediterraneo<\/strong> offre vantaggi unici:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Mindfulness potenziata:<\/strong> La natura amplifica la concentrazione e la presenza.<\/li>\n\n\n\n<li class=\"\"><strong>Rinnovamento energetico:<\/strong> L'aria di mare d\u00e0 energia al corpo e alla mente.<\/li>\n\n\n\n<li class=\"\"><strong>Alleviare lo stress:<\/strong> Il suono delle onde favorisce la meditazione e la calma interiore.<\/li>\n\n\n\n<li class=\"\"><strong>Forza e flessibilit\u00e0:<\/strong> Le asana dello yoga rafforzano la vitalit\u00e0 fisica e armonizzano l'energia.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le sessioni di yoga all'aperto vanno oltre l'esercizio fisico: sono <strong>esperienze olistiche<\/strong> Collegare il respiro, il movimento e la natura.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Partecipate alle sessioni di yoga all'aperto di Dhariya ad Altea<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">All'Inspire Altea, Dhariya offre <strong>lezioni private e di gruppo di yoga in spiaggia<\/strong> all'alba o al tramonto, adatto a principianti e praticanti esperti. Esplorerete le sequenze di yoga, il lavoro sul respiro e la meditazione guidata con <strong>istruzione autentica influenzata dai maestri indiani<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Per saperne di pi\u00f9 sul nostro <a href=\"https:\/\/www.inspirealtea.com\/it\/yoga-ad-altea\/\">Ritiri di yoga a Altea<\/a><\/li>\n\n\n\n<li class=\"\">Leggi il prossimo articolo su <em><a href=\"https:\/\/www.inspirealtea.com\/it\/una-vita-da-yogi-ad-altea-costa-blanca\/\">Una vita da yoga ad Altea<\/a><\/em><\/li>\n\n\n\n<li class=\"\">Scoprite i benefici dello yoga all'aperto a <a href=\"https:\/\/www.yogaalliance.org\/\">Alleanza Yoga<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni sessione \u00e8 un'opportunit\u00e0 per <strong>risvegliare la calma interiore, ripristinare l'equilibrio e abbracciare il benessere<\/strong> in riva al mare.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Perch\u00e9 scegliere Inspire Altea?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con la guida di Dhariya, sperimenterete uno yoga che \u00e8 <strong>autentico, consapevole e trasformativo<\/strong>. Ispirato da maestri quali Sri Ramana Maharshi e Swami Satyananda Saraswati, l'insegnamento di Dhariya integra <strong>profondit\u00e0 spirituale, consapevolezza e precisione<\/strong>. In contrapposizione con il <strong>splendida costa mediterranea<\/strong>, ogni pratica diventa un viaggio di <strong>pace interiore, forza e consapevolezza di s\u00e9<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sunrise-to-sunset-yoga-experiences\"><strong>Esperienze di yoga dall'alba al tramonto<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <em>Ispirare Altea<\/em>, offriamo <strong>corsi e ritiri di yoga all'aperto<\/strong> che fondono il movimento del corpo, la meditazione e l'energia curativa del Mediterraneo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unitevi a noi per i flussi all'alba o per le meditazioni al tramonto in riva al mare: momenti che ristabiliscono l'armonia interiore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2728<a href=\"https:\/\/www.inspirealtea.com\/it\/yoga-ad-altea\/\">Esplora i nostri ritiri yoga<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Riconnettetevi con la natura e risvegliate la vostra calma interiore con lo yoga all'aperto nel Mar Mediterraneo guidato da Dhariya presso Inspire Altea. Sperimentate lo yoga mentale sulla spiaggia all'alba o al tramonto.<\/p>","protected":false},"author":1,"featured_media":846,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[89,88,172],"tags":[175,178,179,168,174,177,180,173,164,176],"class_list":["post-845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-programs-and-packages","category-wellbeing","category-yoga-in-altea","tag-beach-yoga-altea","tag-costa-blanca-retreats","tag-holistic-wellness-altea","tag-inspire-altea","tag-mediterranean-yoga-retreats","tag-mindfulness-yoga","tag-nature-connection","tag-outdoor-yoga-mediterranean-sea","tag-wellness-retreats-spain","tag-yoga-by-the-sea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Outdoor Yoga Mediterranean Sea | Inspire Altea Wellbeing<\/title>\n<meta name=\"description\" content=\"Experience outdoor yoga Mediterranean Sea with Inspire Altea. Breathe, flow, and reconnect with nature through mindful beach yoga sessions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inspirealtea.com\/it\/yoga-allaperto-mare-mediterraneo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yoga By The Mediterranean Sea | A New Dimension Of Practice\" \/>\n<meta property=\"og:description\" content=\"Experience outdoor yoga Mediterranean Sea with Inspire Altea. Breathe, flow, and reconnect with nature through mindful beach yoga sessions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inspirealtea.com\/it\/yoga-allaperto-mare-mediterraneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Yoga, Ayurveda and Hiking | Inspire Altea\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/yogaayurveda.altea\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/inspirealtea\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-04T08:53:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-28T19:03:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1880\" \/>\n\t<meta property=\"og:image:height\" content=\"1253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sergio Cisneros Galea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Cisneros Galea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yoga all'aperto Mare Mediterraneo | Ispirare il benessere di Altea","description":"Provate lo yoga all'aperto nel Mar Mediterraneo con Inspire Altea. Respirate, fluite e riconnettetevi con la natura attraverso sessioni di yoga in spiaggia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inspirealtea.com\/it\/yoga-allaperto-mare-mediterraneo\/","og_locale":"it_IT","og_type":"article","og_title":"Yoga By The Mediterranean Sea | A New Dimension Of Practice","og_description":"Experience outdoor yoga Mediterranean Sea with Inspire Altea. Breathe, flow, and reconnect with nature through mindful beach yoga sessions.","og_url":"https:\/\/www.inspirealtea.com\/it\/yoga-allaperto-mare-mediterraneo\/","og_site_name":"Yoga, Ayurveda and Hiking | Inspire Altea","article_publisher":"https:\/\/www.facebook.com\/yogaayurveda.altea","article_author":"https:\/\/www.facebook.com\/inspirealtea","article_published_time":"2025-11-04T08:53:57+00:00","article_modified_time":"2026-02-28T19:03:51+00:00","og_image":[{"width":1880,"height":1253,"url":"https:\/\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp","type":"image\/webp"}],"author":"Sergio Cisneros Galea","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sergio Cisneros Galea","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#article","isPartOf":{"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/"},"author":{"name":"Sergio Cisneros Galea","@id":"https:\/\/www.inspirealtea.com\/#\/schema\/person\/593043113a0f1ff76db70c2227373e4b"},"headline":"Yoga By The Mediterranean Sea | A New Dimension Of Practice","datePublished":"2025-11-04T08:53:57+00:00","dateModified":"2026-02-28T19:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/"},"wordCount":367,"publisher":{"@id":"https:\/\/www.inspirealtea.com\/#organization"},"image":{"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp?fit=1880%2C1253&ssl=1","keywords":["beach yoga Altea","Costa Blanca retreats","holistic wellness Altea","Inspire Altea","Mediterranean yoga retreats","mindfulness yoga","nature connection","outdoor yoga Mediterranean Sea","wellness retreats Spain","yoga by the sea"],"articleSection":["Programs &amp; Packages","Wellbeing","Yoga"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/","url":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/","name":"Yoga all'aperto Mare Mediterraneo | Ispirare il benessere di Altea","isPartOf":{"@id":"https:\/\/www.inspirealtea.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#primaryimage"},"image":{"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp?fit=1880%2C1253&ssl=1","datePublished":"2025-11-04T08:53:57+00:00","dateModified":"2026-02-28T19:03:51+00:00","description":"Provate lo yoga all'aperto nel Mar Mediterraneo con Inspire Altea. Respirate, fluite e riconnettetevi con la natura attraverso sessioni di yoga in spiaggia.","breadcrumb":{"@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#primaryimage","url":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp?fit=1880%2C1253&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp?fit=1880%2C1253&ssl=1","width":1880,"height":1253,"caption":"Private yoga session in Altea with two participants practicing by the sea in a peaceful setting."},{"@type":"BreadcrumbList","@id":"https:\/\/www.inspirealtea.com\/outdoor-yoga-mediterranean-sea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inspirealtea.com\/"},{"@type":"ListItem","position":2,"name":"Yoga","item":"https:\/\/www.inspirealtea.com\/blog\/yoga-in-altea\/"},{"@type":"ListItem","position":3,"name":"Yoga By The Mediterranean Sea | A New Dimension Of Practice"}]},{"@type":"WebSite","@id":"https:\/\/www.inspirealtea.com\/#website","url":"https:\/\/www.inspirealtea.com\/","name":"Yoga, Ayurveda ed escursioni | Ispirare Altea","description":"Esplora te stesso attraverso Yoga, Ayurveda ed Escursionismo ad Altea, Alicante \u2014 un santuario per il benessere sul Mediterraneo.","publisher":{"@id":"https:\/\/www.inspirealtea.com\/#organization"},"alternateName":"Inspire Altea \u2013 Yoga, Ayurveda & Hiking","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inspirealtea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.inspirealtea.com\/#organization","name":"Yoga, ayurveda ed escursionismo | Inspire Altea","alternateName":"IA Yoga Ayurveda Hike","url":"https:\/\/www.inspirealtea.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.inspirealtea.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/10\/Logo-Inspire-Altea.png?fit=1024%2C1024&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/10\/Logo-Inspire-Altea.png?fit=1024%2C1024&ssl=1","width":1024,"height":1024,"caption":"Yoga, Ayurveda and Hiking | Inspire Altea"},"image":{"@id":"https:\/\/www.inspirealtea.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/yogaayurveda.altea","https:\/\/www.instagram.com\/inspirealtea\/","https:\/\/www.linkedin.com\/in\/sergio-cisneros-galea","https:\/\/www.youtube.com\/@inspirealtea","https:\/\/gravatar.com\/sergiocisnerosgalea"],"description":"Discover holistic wellbeing experiences in Altea that connect body, mind, and nature. From yoga and Ayurveda to guided hiking and personalized retreats \u2014 all designed to help you restore balance, vitality, and inner peace.","email":"inspirealtea@gmail.com","telephone":"+33 6 07 42 58 97","legalName":"Sergio Cisneros Galea","foundingDate":"2019-11-11","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/www.inspirealtea.com\/who-i-am\/"},{"@type":"Person","@id":"https:\/\/www.inspirealtea.com\/#\/schema\/person\/593043113a0f1ff76db70c2227373e4b","name":"Sergio Cisneros Galea","pronouns":"He","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/72e5c7985a9646976d7745f0e7a0ff6cd45f1b3e75497ffc7361970096c61e04?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72e5c7985a9646976d7745f0e7a0ff6cd45f1b3e75497ffc7361970096c61e04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72e5c7985a9646976d7745f0e7a0ff6cd45f1b3e75497ffc7361970096c61e04?s=96&d=mm&r=g","caption":"Sergio Cisneros Galea"},"description":"I'm Sergio Cisneros Galea \u2014 mountain guide, yoga teacher, and Ayurvedic therapist. For the past 16 years, I've had the privilege of walking alongside people on their path of wellbeing, weaving together nature, movement, and self-awareness. I've spent much of my life in the mountains \u2014 the Pyrenees, the Alps, Morocco \u2014 and along the way, yoga and Ayurveda became natural companions to that journey. Together, they shaped what is now Inspire Altea: a small project born from a deep love for the mountains, conscious living, and the simple joy of helping people feel at home in their bodies and in nature. I work between France and Spain's Costa Blanca, offering mountain retreats, mindful hiking, and holistic health programs. I'm lucky to speak Spanish, French, English, Catalan, and Italian \u2014 which means I get to share this work with people from many different places.","sameAs":["https:\/\/www.inspirealtea.com","https:\/\/www.facebook.com\/inspirealtea","https:\/\/www.instagram.com\/inspirealtea","https:\/\/es.linkedin.com\/in\/sergio-cisneros-galea","https:\/\/www.youtube.com\/@inspirealtea"],"gender":"hombre","knowsLanguage":["ingles","franc\u00e9s","espa\u00f1ol","italiano y catal\u00e1n"],"url":"https:\/\/www.inspirealtea.com\/it\/author\/sergio\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.inspirealtea.com\/wp-content\/uploads\/2025\/11\/pexels-photo-5928258.webp?fit=1880%2C1253&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/posts\/845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/comments?post=845"}],"version-history":[{"count":2,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/posts\/845\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/posts\/845\/revisions\/984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/media\/846"}],"wp:attachment":[{"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/media?parent=845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/categories?post=845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inspirealtea.com\/it\/wp-json\/wp\/v2\/tags?post=845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}